{"id":2249,"count":1,"description":"","link":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","name":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas","slug":"dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - Alas Medios<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - Alas Medios\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/\",\"name\":\"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - Alas Medios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - Alas Medios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","og_locale":"es_MX","og_type":"article","og_title":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - Alas Medios","og_url":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","og_site_name":"Alas Medios","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","url":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","name":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - Alas Medios","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags\/2249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts?tags=2249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}