{"id":7917,"date":"2026-02-24T06:03:00","date_gmt":"2026-02-24T12:03:00","guid":{"rendered":"https:\/\/www.alasmedios.com\/?p=7917"},"modified":"2026-02-23T21:11:28","modified_gmt":"2026-02-24T03:11:28","slug":"tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes","status":"publish","type":"post","link":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/","title":{"rendered":"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La oficina de <strong>ONU M\u00e9xico<\/strong> expres\u00f3 su solidaridad y envi\u00f3 <strong>condolencias por la p\u00e9rdida de vidas<\/strong> registrada durante la compleja jornada derivada del operativo para capturar a <strong>Nemesio Oseguera<\/strong>, identificado como l\u00edder del <strong>C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un mensaje difundido en redes sociales, el organismo internacional lament\u00f3 el fallecimiento de <strong>agentes de las Fuerzas Armadas<\/strong> que murieron en el cumplimiento de su deber, en medio de las acciones emprendidas contra el grupo criminal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CONTIN\u00daA LEYENDO: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/23\/violencia-tras-caida-de-el-mencho-paraliza-deporte-en-mexico\/\" data-type=\"post\" data-id=\"7901\">Violencia tras ca\u00edda de \u201cEl Mencho\u201d paraliza deporte en M\u00e9xico<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su posicionamiento, <strong>ONU M\u00e9xico<\/strong> reiter\u00f3 su disposici\u00f3n para acompa\u00f1ar al <strong>gobierno de M\u00e9xico<\/strong> en los esfuerzos orientados a <strong>fortalecer la seguridad<\/strong> y enfrentar a la <strong>delincuencia organizada<\/strong>, subrayando la importancia de actuar en estricto <strong>apego al Estado de Derecho<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pronunciamiento se da tras una jornada marcada por hechos violentos vinculados al operativo dirigido contra el presunto l\u00edder del CJNG, un episodio que dej\u00f3 v\u00edctimas mortales y reaviv\u00f3 el debate sobre los desaf\u00edos que enfrenta el pa\u00eds en materia de seguridad.<\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/atencion-psicologica-y-nutricion-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/sabia-que-en-hidalgo-jovenes-pueden-acceder-a-atencion-psicologica-y-nutricion-gratuita\/\">\u00bfSab\u00eda que en Hidalgo j\u00f3venes pueden acceder a atenci\u00f3n psicol\u00f3gica y nutrici\u00f3n gratuita?<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/Uniones-forzadas-ninas-en-centroamerica-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/3-9-millones-de-ninas-y-mujeres-en-centroamerica-se-casaron-antes-de-los-15-anos\/\">3.9 millones de ni\u00f1as y mujeres en Centroam\u00e9rica se casaron antes de los 15 a\u00f1os<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/Parque-Nacional-El-Chico-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/parque-nacional-el-chico-scarabajo-descortezador\/\">Parque Nacional El Chico: cient\u00edficos de la UAEH enfrentan al escarabajo descortezador<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La oficina de ONU M\u00e9xico expres\u00f3 su solidaridad y envi\u00f3 condolencias por la p\u00e9rdida de vidas registrada durante la compleja<\/p>\n","protected":false},"author":4,"featured_media":7918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","iawp_total_views":0,"footnotes":""},"categories":[3222,3229],"tags":[166,440,182],"class_list":["post-7917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mexico","category-mundo-extranjero","tag-mexico","tag-onu","tag-violencia"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-150x150.jpg","medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-300x169.jpg","medium_large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-768x432.jpg","large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-1024x576.jpg","1536x1536":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","2048x2048":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","colormag-highlighted-post":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-390x205.jpg","colormag-featured-post-small":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-130x90.jpg","colormag-featured-image":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-800x445.jpg","colormag-default-news":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-150x150.jpg","colormag-featured-image-large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-1200x600.jpg"},"magazineBlocksPostAuthor":{"name":"Keila Rodr\u00edguez Pe\u00f1a","avatar":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"La oficina de ONU M\u00e9xico expres\u00f3 su solidaridad y envi\u00f3 condolencias por la p\u00e9rdida de vidas registrada durante la compleja","magazineBlocksPostCategories":["M\u00e9xico","Mundo"],"magazineBlocksPostViewCount":94,"magazineBlocksPostReadTime":1,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg",1200,675,false],"medium":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"Keila Rodr\u00edguez Pe\u00f1a","author_link":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-3222\">M\u00e9xico<\/a> <a href=\"#\" class=\"category-link category-link-3229\">Mundo<\/a>","videoUrl":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes - Alas Medios<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes - Alas Medios\" \/>\r\n<meta property=\"og:description\" content=\"La oficina de ONU M\u00e9xico expres\u00f3 su solidaridad y envi\u00f3 condolencias por la p\u00e9rdida de vidas registrada durante la compleja\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-02-24T12:03:00+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"675\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/\"},\"author\":{\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\"},\"headline\":\"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes\",\"datePublished\":\"2026-02-24T12:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg\",\"keywords\":[\"M\u00e9xico\",\"ONU\",\"violencia\"],\"articleSection\":[\"M\u00e9xico\",\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/\",\"name\":\"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes - Alas Medios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg\",\"datePublished\":\"2026-02-24T12:03:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/02\\\/24\\\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\",\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"caption\":\"Keila Rodr\u00edguez Pe\u00f1a\"},\"sameAs\":[\"http:\\\/\\\/www.alasmedios.com\"],\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/author\\\/keila\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes - Alas Medios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/","og_locale":"es_MX","og_type":"article","og_title":"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes - Alas Medios","og_description":"La oficina de ONU M\u00e9xico expres\u00f3 su solidaridad y envi\u00f3 condolencias por la p\u00e9rdida de vidas registrada durante la compleja","og_url":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/","og_site_name":"Alas Medios","article_published_time":"2026-02-24T12:03:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","type":"image\/jpeg"}],"author":"Keila Rodr\u00edguez Pe\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Keila Rodr\u00edguez Pe\u00f1a","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#article","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/"},"author":{"name":"Keila Rodr\u00edguez Pe\u00f1a","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34"},"headline":"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes","datePublished":"2026-02-24T12:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","keywords":["M\u00e9xico","ONU","violencia"],"articleSection":["M\u00e9xico","Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/","url":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/","name":"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes - Alas Medios","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#primaryimage"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","datePublished":"2026-02-24T12:03:00+00:00","breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#primaryimage","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/02\/Tras-operativo-contra-El-Mencho-ONU-Mexico-lamenta-muertes.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/02\/24\/tras-operativo-contra-el-mencho-onu-mexico-lamenta-muertes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"Tras operativo contra \u201cEl Mencho\u201d, ONU M\u00e9xico lamenta muertes"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34","name":"Keila Rodr\u00edguez Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","caption":"Keila Rodr\u00edguez Pe\u00f1a"},"sameAs":["https:\/\/www.alasmedios.com"],"url":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/7917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/comments?post=7917"}],"version-history":[{"count":1,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/7917\/revisions"}],"predecessor-version":[{"id":7919,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/7917\/revisions\/7919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media\/7918"}],"wp:attachment":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media?parent=7917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/categories?post=7917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags?post=7917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}