{"id":3606,"date":"2025-02-18T14:58:23","date_gmt":"2025-02-18T20:58:23","guid":{"rendered":"https:\/\/www.alasmedios.com\/?p=3606"},"modified":"2025-02-18T14:58:26","modified_gmt":"2025-02-18T20:58:26","slug":"condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija","status":"publish","type":"post","link":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/","title":{"rendered":"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija"},"content":{"rendered":"\n<p>Un tribunal en Australia sentenci\u00f3 a prisi\u00f3n a una pareja por negligencia grave tras mantener a su hija en un estado de desnutrici\u00f3n extrema. <\/p>\n\n\n\n<p>La joven, de 17 a\u00f1os al momento de ser hospitalizada, pesaba apenas 27.3 kilos, su piel estaba descamada y su cabello quebradizo. <\/p>\n\n\n\n<p>Su estado era tan cr\u00edtico que los m\u00e9dicos tem\u00edan que sufriera un paro card\u00edaco.<\/p>\n\n\n\n<p>A pesar de recibir clases de piano y ballet, la adolescente viv\u00eda aislada y con una alimentaci\u00f3n inadecuada basada en una dieta vegana deficiente. <\/p>\n\n\n\n<p>Su desarrollo f\u00edsico y emocional se vio gravemente afectado: no mostraba signos de pubertad y ve\u00eda programas infantiles como <em>Teletubbies<\/em> y <em>Frozen<\/em>. <\/p>\n\n\n\n<p>Sus padres, lejos de reconocer el problema, falsificaron su acta de nacimiento para hacerla parecer m\u00e1s joven y evitar sospechas.<\/p>\n\n\n\n<p>CONTIN\u00daA LEYENDO: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/17\/corre-con-tu-amigo-carrera-en-hidalgo-a-favor-de-los-perros-en-situacion-de-calle\/\" data-type=\"post\" data-id=\"3601\">Corre con tu Amigo: carrera en Hidalgo a favor de los perros en situaci\u00f3n de calle<\/a><\/p>\n\n\n\n<p>Profesores de danza alertaron a las autoridades tras notar su estado, lo que llev\u00f3 a su hospitalizaci\u00f3n y a la intervenci\u00f3n del Estado. <\/p>\n\n\n\n<p>En el juicio, la jueza Linda Black determin\u00f3 que los padres, aunque aseguraban amarla, no cumplieron con su deber de protegerla y permitirle desarrollarse.<\/p>\n\n\n\n<p>El padre fue condenado a seis a\u00f1os y medio de prisi\u00f3n, y la madre a cinco a\u00f1os. <\/p>\n\n\n\n<p>La joven, ahora de 20 a\u00f1os, ha recuperado peso bajo el cuidado de profesionales.<\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/justicia-atencion-a-comunidades-indigenas-Puebla-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/buscan-acercar-justicia-y-proteccion-a-comunidades-indigenas-y-grupos-vulnerables-en-puebla\/\">Buscan acercar justicia y protecci\u00f3n a comunidades ind\u00edgenas y grupos vulnerables en Puebla<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/Mundial-Mujeres-LIBRES-Hidalgo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/arranca-mundial-mujeres-libres-hidalgo-sale-a-la-cancha-con-33-equipos\/\">Arranca Mundial Mujeres LIBRES: Hidalgo sale a la cancha con 33 equipos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/Puebla-detencion-de-124-personas-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/mas-de-120-detenidos-en-puebla-en-solo-10-dias-decomisan-armas-droga-y-miles-de-litros-de-gas-lp\/\">M\u00e1s de 120 detenidos en Puebla en solo 10 d\u00edas; decomisan armas, droga y miles de litros de gas LP<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Un tribunal en Australia sentenci\u00f3 a prisi\u00f3n a una pareja por negligencia grave tras mantener a su hija en un<\/p>\n","protected":false},"author":4,"featured_media":3607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","iawp_total_views":0,"footnotes":""},"categories":[45],"tags":[1359,1211,1360,182],"class_list":["post-3606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ellas-dicen","tag-adolescente","tag-australia","tag-desnutricion","tag-violencia"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-150x150.png","medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-300x157.png","medium_large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-768x402.png","large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-1024x536.png","1536x1536":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","2048x2048":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","colormag-highlighted-post":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-392x272.png","colormag-featured-post-medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-390x205.png","colormag-featured-post-small":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-130x90.png","colormag-featured-image":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-800x445.png","colormag-default-news":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-150x150.png","colormag-featured-image-large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-1200x600.png"},"magazineBlocksPostAuthor":{"name":"Keila Rodr\u00edguez Pe\u00f1a","avatar":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Un tribunal en Australia sentenci\u00f3 a prisi\u00f3n a una pareja por negligencia grave tras mantener a su hija en un","magazineBlocksPostCategories":["Ellas Dicen"],"magazineBlocksPostViewCount":269,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png",1200,628,false],"medium":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-300x157.png",300,157,true],"thumbnail":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada-150x150.png",150,150,true]},"magazine_blocks_author":{"display_name":"Keila Rodr\u00edguez Pe\u00f1a","author_link":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-45\">Ellas Dicen<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija - Alas Medios<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija - Alas Medios\" \/>\r\n<meta property=\"og:description\" content=\"Un tribunal en Australia sentenci\u00f3 a prisi\u00f3n a una pareja por negligencia grave tras mantener a su hija en un\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-02-18T20:58:23+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-02-18T20:58:26+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"628\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/\"},\"author\":{\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\"},\"headline\":\"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija\",\"datePublished\":\"2025-02-18T20:58:23+00:00\",\"dateModified\":\"2025-02-18T20:58:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/\"},\"wordCount\":251,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portada.png\",\"keywords\":[\"adolescente\",\"Australia\",\"desnutrici\u00f3n\",\"violencia\"],\"articleSection\":[\"Ellas Dicen\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/\",\"name\":\"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija - Alas Medios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portada.png\",\"datePublished\":\"2025-02-18T20:58:23+00:00\",\"dateModified\":\"2025-02-18T20:58:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portada.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portada.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2025\\\/02\\\/18\\\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\",\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"caption\":\"Keila Rodr\u00edguez Pe\u00f1a\"},\"sameAs\":[\"http:\\\/\\\/www.alasmedios.com\"],\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/author\\\/keila\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija - Alas Medios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/","og_locale":"es_MX","og_type":"article","og_title":"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija - Alas Medios","og_description":"Un tribunal en Australia sentenci\u00f3 a prisi\u00f3n a una pareja por negligencia grave tras mantener a su hija en un","og_url":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/","og_site_name":"Alas Medios","article_published_time":"2025-02-18T20:58:23+00:00","article_modified_time":"2025-02-18T20:58:26+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","type":"image\/png"}],"author":"Keila Rodr\u00edguez Pe\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Keila Rodr\u00edguez Pe\u00f1a","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#article","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/"},"author":{"name":"Keila Rodr\u00edguez Pe\u00f1a","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34"},"headline":"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija","datePublished":"2025-02-18T20:58:23+00:00","dateModified":"2025-02-18T20:58:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/"},"wordCount":251,"commentCount":0,"publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","keywords":["adolescente","Australia","desnutrici\u00f3n","violencia"],"articleSection":["Ellas Dicen"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/","url":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/","name":"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija - Alas Medios","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#primaryimage"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","datePublished":"2025-02-18T20:58:23+00:00","dateModified":"2025-02-18T20:58:26+00:00","breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#primaryimage","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2025\/02\/portada.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/2025\/02\/18\/condenan-a-padres-en-australia-por-desnutricion-extrema-de-su-hija\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"Condenan a padres en Australia por desnutrici\u00f3n extrema de su hija"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34","name":"Keila Rodr\u00edguez Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","caption":"Keila Rodr\u00edguez Pe\u00f1a"},"sameAs":["http:\/\/www.alasmedios.com"],"url":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/3606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/comments?post=3606"}],"version-history":[{"count":1,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/3606\/revisions"}],"predecessor-version":[{"id":3608,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/3606\/revisions\/3608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media\/3607"}],"wp:attachment":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media?parent=3606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/categories?post=3606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags?post=3606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}