{"id":2046,"date":"2024-09-11T15:16:04","date_gmt":"2024-09-11T20:16:04","guid":{"rendered":"https:\/\/www.alasmedios.com\/?p=2046"},"modified":"2024-09-11T15:16:11","modified_gmt":"2024-09-11T20:16:11","slug":"sumision-quimica-violencia-silenciosa-y-la-revictimizacion","status":"publish","type":"post","link":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/","title":{"rendered":"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n"},"content":{"rendered":"\n<p>La <strong>sumisi\u00f3n qu\u00edmica<\/strong> es una pr\u00e1ctica violenta y grave que ocurre cuando una persona es drogada sin su consentimiento para ser agredida, usualmente de forma sexual. <\/p>\n\n\n\n<p>Este tipo de ataque se caracteriza por la administraci\u00f3n de sustancias que alteran la conciencia de la v\u00edctima, dej\u00e1ndola vulnerable e indefensa. <\/p>\n\n\n\n<p>Lo que distingue a esta forma de violencia es que, adem\u00e1s del trauma f\u00edsico y psicol\u00f3gico que puede causar, conlleva un profundo estigma social que muchas veces revictimiza a quienes la sufren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-estigmatizacion-de-las-victimas-perder-el-control-o-no-recordar\">La estigmatizaci\u00f3n de las v\u00edctimas: &#8220;perder el control&#8221; o &#8220;no recordar&#8221;<\/h3>\n\n\n\n<p>Cuando una v\u00edctima de sumisi\u00f3n qu\u00edmica se atreve a denunciar, se enfrenta al doloroso proceso de reconstruir los hechos, a una serie de juicios y comentarios que cuestionan su integridad. <\/p>\n\n\n\n<p>CONTIN\u00daA LEYENDO: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/10\/segundo-depredador-en-el-caso-pelicot-sale-a-la-luz\/\">Segundo depredador en el caso Pelicot sale a la luz\u00a0<\/a><\/p>\n\n\n\n<p>Comentarios como &#8220;perdiste el control&#8221;, &#8220;\u00bfc\u00f3mo no te diste cuenta?&#8221; o &#8220;si no lo recuerdas, \u00bfc\u00f3mo sabes lo que pas\u00f3?&#8221; son comunes y altamente da\u00f1inos. <\/p>\n\n\n\n<p>Esta revictimizaci\u00f3n parte de la idea de que las v\u00edctimas debieron haber &#8220;evitado&#8221; la situaci\u00f3n o que de alguna manera fueron responsables de lo ocurrido.<\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/C_x_dPnhXxQ\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/C_x_dPnhXxQ\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/C_x_dPnhXxQ\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por Grupo Alas Medios (@grupo.alasmedios)<\/a><\/p><\/div><\/blockquote>\n<script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<p>El <strong>estigma<\/strong> alrededor de la sumisi\u00f3n qu\u00edmica refuerza el mito de que una persona es vulnerable \u00fanicamente si &#8220;no cuida lo suficiente&#8221; su entorno o decisiones. <\/p>\n\n\n\n<p>En realidad, las sustancias utilizadas son, en su mayor\u00eda, imposibles de detectar para quienes las consumen de forma involuntaria. <\/p>\n\n\n\n<p>Los efectos son r\u00e1pidos y devastadores, anulando la capacidad de respuesta y dejando a las v\u00edctimas sin control alguno sobre lo que sucede a continuaci\u00f3n.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-la-invisibilizacion-del-agresor\">La invisibilizaci\u00f3n del agresor<\/h5>\n\n\n\n<p>Uno de los aspectos m\u00e1s preocupantes del estigma hacia las v\u00edctimas es c\u00f3mo se desv\u00eda la atenci\u00f3n del verdadero culpable: el agresor. <\/p>\n\n\n\n<p>TE PUEDE INTERESAR: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/05\/51-hombres-a-juicio-por-violacion-sistematica-en-francia\/\">51 hombres a juicio por violaci\u00f3n sistem\u00e1tica en Francia<\/a><\/p>\n\n\n\n<p>En lugar de enfocar el discurso en quienes cometen estos actos de violencia, se culpa a la v\u00edctima por &#8220;no haber tomado las precauciones necesarias&#8221;. <\/p>\n\n\n\n<p>Esto refuerza la impunidad de los agresores, desanima a muchas personas a denunciar por miedo a no ser cre\u00eddas o a ser juzgadas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-romper-con-el-estigma\">Romper con el estigma<\/h3>\n\n\n\n<p>Para combatir la violencia de la sumisi\u00f3n qu\u00edmica, es vital cuestionar y desmantelar el estigma que recae sobre las v\u00edctimas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/1-1024x536.png\" alt=\"\" class=\"wp-image-2051\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/1-1024x536.png 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/1-300x157.png 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/1-768x402.png 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/1-390x205.png 390w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En lugar de cuestionar su comportamiento, debemos enfocarnos en educar sobre la realidad de este tipo de violencia y la importancia de la empat\u00eda y el apoyo a quienes la sufren. <\/p>\n\n\n\n<p><strong>Ninguna persona deber\u00eda cargar con la culpa por la agresi\u00f3n que sufri\u00f3<\/strong>. <\/p>\n\n\n\n<p>Cada vez que repetimos o validamos comentarios que sugieren que una v\u00edctima &#8220;perdi\u00f3 el control&#8221;, estamos contribuyendo a una cultura de silencio e impunidad.<\/p>\n\n\n\n<p>CONTIN\u00daA LEYENDO: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/03\/ile-un-derecho-fundamental-para-la-salud-y-la-autonomia\/\">ILE: un derecho fundamental para la salud y la autonom\u00eda<\/a><\/p>\n\n\n\n<p>El primer paso para erradicar la sumisi\u00f3n qu\u00edmica es visibilizar el problema y reconocer que la \u00fanica persona responsable de un ataque es el agresor. <\/p>\n\n\n\n<p><strong>Creer a las v\u00edctimas<\/strong> y cuestionar los estereotipos que alimentan el estigma es un acto de justicia y una forma de empezar a romper el ciclo de violencia.<\/p>\n\n\n\n<p>Por <strong><a href=\"https:\/\/www.instagram.com\/keila_kait\/\">Keila Itzel Rodr\u00edguez Pe\u00f1a<\/a><\/strong><\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/justicia-atencion-a-comunidades-indigenas-Puebla-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/buscan-acercar-justicia-y-proteccion-a-comunidades-indigenas-y-grupos-vulnerables-en-puebla\/\">Buscan acercar justicia y protecci\u00f3n a comunidades ind\u00edgenas y grupos vulnerables en Puebla<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/Mundial-Mujeres-LIBRES-Hidalgo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/arranca-mundial-mujeres-libres-hidalgo-sale-a-la-cancha-con-33-equipos\/\">Arranca Mundial Mujeres LIBRES: Hidalgo sale a la cancha con 33 equipos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/Puebla-detencion-de-124-personas-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/mas-de-120-detenidos-en-puebla-en-solo-10-dias-decomisan-armas-droga-y-miles-de-litros-de-gas-lp\/\">M\u00e1s de 120 detenidos en Puebla en solo 10 d\u00edas; decomisan armas, droga y miles de litros de gas LP<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta y grave que ocurre cuando una persona es drogada sin su consentimiento para<\/p>\n","protected":false},"author":4,"featured_media":2050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","iawp_total_views":1,"footnotes":""},"categories":[45,44],"tags":[53,136,594,121],"class_list":["post-2046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ellas-dicen","category-sexualidad","tag-mujeres","tag-salud","tag-sumision-quimica","tag-violencia-de-genero-2"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-150x150.png","medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-300x157.png","medium_large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-768x402.png","large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-1024x536.png","1536x1536":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","2048x2048":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","colormag-highlighted-post":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-392x272.png","colormag-featured-post-medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-390x205.png","colormag-featured-post-small":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-130x90.png","colormag-featured-image":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-800x445.png","colormag-default-news":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-150x150.png","colormag-featured-image-large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-1200x600.png"},"magazineBlocksPostAuthor":{"name":"Keila Rodr\u00edguez Pe\u00f1a","avatar":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta y grave que ocurre cuando una persona es drogada sin su consentimiento para","magazineBlocksPostCategories":["Ellas Dicen","Salud y Sexualidad"],"magazineBlocksPostViewCount":413,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png",1200,628,false],"medium":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-300x157.png",300,157,true],"thumbnail":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica-150x150.png",150,150,true]},"magazine_blocks_author":{"display_name":"Keila Rodr\u00edguez Pe\u00f1a","author_link":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-45\">Ellas Dicen<\/a> <a href=\"#\" class=\"category-link category-link-44\">Salud y Sexualidad<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n<\/title>\r\n<meta name=\"description\" content=\"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta que ocurre cuando una persona es drogada sin su consentimiento para ser agredida\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta que ocurre cuando una persona es drogada sin su consentimiento para ser agredida\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-09-11T20:16:04+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-09-11T20:16:11+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"628\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/\"},\"author\":{\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\"},\"headline\":\"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n\",\"datePublished\":\"2024-09-11T20:16:04+00:00\",\"dateModified\":\"2024-09-11T20:16:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/\"},\"wordCount\":576,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/sumision-quimica.png\",\"keywords\":[\"Mujeres\",\"Salud\",\"Sumisi\u00f3n qu\u00edmica\",\"violencia de g\u00e9nero\"],\"articleSection\":[\"Ellas Dicen\",\"Salud y Sexualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/\",\"name\":\"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/sumision-quimica.png\",\"datePublished\":\"2024-09-11T20:16:04+00:00\",\"dateModified\":\"2024-09-11T20:16:11+00:00\",\"description\":\"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta que ocurre cuando una persona es drogada sin su consentimiento para ser agredida\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/sumision-quimica.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/sumision-quimica.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/09\\\/11\\\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\",\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"caption\":\"Keila Rodr\u00edguez Pe\u00f1a\"},\"sameAs\":[\"http:\\\/\\\/www.alasmedios.com\"],\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/author\\\/keila\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n","description":"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta que ocurre cuando una persona es drogada sin su consentimiento para ser agredida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/","og_locale":"es_MX","og_type":"article","og_title":"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n","og_description":"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta que ocurre cuando una persona es drogada sin su consentimiento para ser agredida","og_url":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/","og_site_name":"Alas Medios","article_published_time":"2024-09-11T20:16:04+00:00","article_modified_time":"2024-09-11T20:16:11+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","type":"image\/png"}],"author":"Keila Rodr\u00edguez Pe\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Keila Rodr\u00edguez Pe\u00f1a","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#article","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/"},"author":{"name":"Keila Rodr\u00edguez Pe\u00f1a","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34"},"headline":"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n","datePublished":"2024-09-11T20:16:04+00:00","dateModified":"2024-09-11T20:16:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/"},"wordCount":576,"commentCount":0,"publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","keywords":["Mujeres","Salud","Sumisi\u00f3n qu\u00edmica","violencia de g\u00e9nero"],"articleSection":["Ellas Dicen","Salud y Sexualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/","url":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/","name":"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#primaryimage"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","datePublished":"2024-09-11T20:16:04+00:00","dateModified":"2024-09-11T20:16:11+00:00","description":"La sumisi\u00f3n qu\u00edmica es una pr\u00e1ctica violenta que ocurre cuando una persona es drogada sin su consentimiento para ser agredida","breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#primaryimage","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/09\/sumision-quimica.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/09\/11\/sumision-quimica-violencia-silenciosa-y-la-revictimizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"Sumisi\u00f3n qu\u00edmica: violencia silenciosa y la revictimizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34","name":"Keila Rodr\u00edguez Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","caption":"Keila Rodr\u00edguez Pe\u00f1a"},"sameAs":["http:\/\/www.alasmedios.com"],"url":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/2046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/comments?post=2046"}],"version-history":[{"count":1,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/2046\/revisions"}],"predecessor-version":[{"id":2052,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/2046\/revisions\/2052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media\/2050"}],"wp:attachment":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media?parent=2046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/categories?post=2046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags?post=2046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}