{"id":1862,"date":"2024-08-25T14:22:13","date_gmt":"2024-08-25T20:22:13","guid":{"rendered":"https:\/\/www.alasmedios.com\/?p=1862"},"modified":"2024-08-25T14:22:15","modified_gmt":"2024-08-25T20:22:15","slug":"lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco","status":"publish","type":"post","link":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/","title":{"rendered":"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco"},"content":{"rendered":"\n<p>La Comisi\u00f3n Estatal para el Desarrollo Sostenible de los Pueblos Ind\u00edgenas (CEDSPI) ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la &#8220;Casa de la Mujer Ind\u00edgena&#8221; en la regi\u00f3n de las Tres Huastecas. <\/p>\n\n\n\n<p>Este proyecto, que comenzar\u00e1 su construcci\u00f3n en Atlapexco este a\u00f1o, est\u00e1 dise\u00f1ado para proporcionar un entorno seguro y digno donde las mujeres ind\u00edgenas puedan recibir atenci\u00f3n integral durante el embarazo, el parto y el posparto.<\/p>\n\n\n\n<p>La Casa de la Mujer Ind\u00edgena est\u00e1 destinada a ser un pilar de apoyo para m\u00e1s de 43 mil mujeres en Atlapexco, Huautla, Xochiatipan y Yahualica, con un impacto indirecto en otros municipios cercanos como Calnali, Lolotla, Huazalingo, San Felipe Orizatl\u00e1n, Jaltoc\u00e1n y Huejutla. <\/p>\n\n\n\n<p>El proyecto est\u00e1 alineado con el objetivo de reducir significativamente los riesgos asociados con el embarazo en estas comunidades, donde las mujeres frecuentemente enfrentan barreras para acceder a servicios de salud de calidad.<\/p>\n\n\n\n<p>CONTIN\u00daA LEYENDO: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/24\/nuga-nui-nui-nuga-exposicion-en-pachuca\/\">Nuga Nu\u2019i, Nu\u2019i Nuga: exposici\u00f3n en Pachuca<\/a><\/p>\n\n\n\n<p>En su primera etapa, la construcci\u00f3n del centro recibir\u00e1 una inversi\u00f3n superior a los 7.8 millones de pesos, que se destinar\u00e1n tanto a la infraestructura como al equipamiento necesario para que las instalaciones funcionen plenamente. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1866\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-5-1024x679.jpg\" alt=\"\" class=\"wp-image-1866\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-5-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-5-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-5-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-5-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-5.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1869\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-2-1024x679.jpg\" alt=\"\" class=\"wp-image-1869\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-2-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-2-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-2-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-2-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-2.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1868\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-1-1024x679.jpg\" alt=\"\" class=\"wp-image-1868\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-1-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-1-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-1-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-1-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1870\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-7-1024x679.jpg\" alt=\"\" class=\"wp-image-1870\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-7-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-7-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-7-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-7-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-7.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1865\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1-1024x679.jpg\" alt=\"\" class=\"wp-image-1865\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1864\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1024x679.jpg\" alt=\"\" class=\"wp-image-1864\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>La Casa contar\u00e1 con salas de exploraci\u00f3n, \u00e1reas de parto, un temazcal para terapias tradicionales, y un jard\u00edn bot\u00e1nico destinado a la conservaci\u00f3n de plantas medicinales utilizadas en la medicina ind\u00edgena.<\/p>\n\n\n\n<p>El proyecto no solo se centra en la infraestructura f\u00edsica, sino tambi\u00e9n en el fortalecimiento del rol de las parteras tradicionales. <\/p>\n\n\n\n<p>A trav\u00e9s de programas de capacitaci\u00f3n y certificaci\u00f3n, estas mujeres ser\u00e1n dotadas de herramientas y conocimientos actualizados que les permitir\u00e1n continuar su invaluable labor en sus comunidades. <\/p>\n\n\n\n<p>Adem\u00e1s, se busca reconocer formalmente su contribuci\u00f3n a la salud materna, asegurando que reciban el respeto y el apoyo que merecen.<\/p>\n\n\n\n<p>TE PUEDE INTERESAR: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/21\/mujeres-con-alas-maria-sojob\/\">Mar\u00eda Sojob<\/a><\/p>\n\n\n\n<p>El alcalde de Atlapexco, Joel Nochebuena Hern\u00e1ndez, destac\u00f3 la importancia de este proyecto para el municipio y la regi\u00f3n, se\u00f1alando que la disposici\u00f3n de su administraci\u00f3n fue clave para que Atlapexco fuera seleccionado como sede. <\/p>\n\n\n\n<p>El municipio colabor\u00f3 estrechamente con los estudios t\u00e9cnicos y don\u00f3 un terreno de 8 mil 275 metros cuadrados para la construcci\u00f3n del centro, ubicado estrat\u00e9gicamente cerca del Cecyteh y del hospital regional.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"1871\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-8-1024x679.jpg\" alt=\"\" class=\"wp-image-1871\" srcset=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-8-1024x679.jpg 1024w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-8-300x199.jpg 300w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-8-768x509.jpg 768w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-8-1536x1018.jpg 1536w, https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-8.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Prisco Manuel Guti\u00e9rrez, titular de Pueblos Ind\u00edgenas, reafirm\u00f3 el compromiso del gobierno estatal, encabezado por Julio Menchaca, de trabajar por la justicia y la equidad:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Los ind\u00edgenas somos el coraz\u00f3n de Hidalgo. La Casa de la Mujer Ind\u00edgena es un acto de reivindicaci\u00f3n, dignidad y respeto para cuidar la vida y propiciar el desarrollo sostenible en las comunidades originarias&#8221; <\/p>\n<\/blockquote>\n\n\n\n<p>Este proyecto se enmarca dentro de una pol\u00edtica m\u00e1s amplia que busca asegurar que los pueblos ind\u00edgenas tengan acceso a servicios de salud y apoyo social que respeten y valoren sus tradiciones y necesidades espec\u00edficas.<\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/justicia-atencion-a-comunidades-indigenas-Puebla-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/buscan-acercar-justicia-y-proteccion-a-comunidades-indigenas-y-grupos-vulnerables-en-puebla\/\">Buscan acercar justicia y protecci\u00f3n a comunidades ind\u00edgenas y grupos vulnerables en Puebla<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/Mundial-Mujeres-LIBRES-Hidalgo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/arranca-mundial-mujeres-libres-hidalgo-sale-a-la-cancha-con-33-equipos\/\">Arranca Mundial Mujeres LIBRES: Hidalgo sale a la cancha con 33 equipos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/Puebla-detencion-de-124-personas-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/12\/mas-de-120-detenidos-en-puebla-en-solo-10-dias-decomisan-armas-droga-y-miles-de-litros-de-gas-lp\/\">M\u00e1s de 120 detenidos en Puebla en solo 10 d\u00edas; decomisan armas, droga y miles de litros de gas LP<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Estatal para el Desarrollo Sostenible de los Pueblos Ind\u00edgenas (CEDSPI) ha tomado una iniciativa fundamental al concretar la<\/p>\n","protected":false},"author":4,"featured_media":1863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","iawp_total_views":0,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-1862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-150x150.jpg","medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-300x199.jpg","medium_large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-768x509.jpg","large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-1024x679.jpg","1536x1536":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-1536x1018.jpg","2048x2048":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg","colormag-highlighted-post":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-390x205.jpg","colormag-featured-post-small":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-130x90.jpg","colormag-featured-image":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-800x445.jpg","colormag-default-news":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-150x150.jpg","colormag-featured-image-large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"Keila Rodr\u00edguez Pe\u00f1a","avatar":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"La Comisi\u00f3n Estatal para el Desarrollo Sostenible de los Pueblos Ind\u00edgenas (CEDSPI) ha tomado una iniciativa fundamental al concretar la","magazineBlocksPostCategories":["Inicio"],"magazineBlocksPostViewCount":233,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg",2048,1357,false],"medium":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-300x199.jpg",300,199,true],"thumbnail":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"Keila Rodr\u00edguez Pe\u00f1a","author_link":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-39\">Inicio<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco<\/title>\r\n<meta name=\"description\" content=\"La CEDSPI ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la &quot;Casa de la Mujer Ind\u00edgena&quot; en la regi\u00f3n de las Tres Huastecas\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco\" \/>\r\n<meta property=\"og:description\" content=\"La CEDSPI ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la &quot;Casa de la Mujer Ind\u00edgena&quot; en la regi\u00f3n de las Tres Huastecas\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-08-25T20:22:13+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-08-25T20:22:15+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1357\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/\"},\"author\":{\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\"},\"headline\":\"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco\",\"datePublished\":\"2024-08-25T20:22:13+00:00\",\"dateModified\":\"2024-08-25T20:22:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg\",\"articleSection\":[\"Inicio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/\",\"name\":\"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg\",\"datePublished\":\"2024-08-25T20:22:13+00:00\",\"dateModified\":\"2024-08-25T20:22:15+00:00\",\"description\":\"La CEDSPI ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la \\\"Casa de la Mujer Ind\u00edgena\\\" en la regi\u00f3n de las Tres Huastecas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg\",\"width\":2048,\"height\":1357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2024\\\/08\\\/25\\\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\",\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"caption\":\"Keila Rodr\u00edguez Pe\u00f1a\"},\"sameAs\":[\"http:\\\/\\\/www.alasmedios.com\"],\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/author\\\/keila\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco","description":"La CEDSPI ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la \"Casa de la Mujer Ind\u00edgena\" en la regi\u00f3n de las Tres Huastecas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/","og_locale":"es_MX","og_type":"article","og_title":"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco","og_description":"La CEDSPI ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la \"Casa de la Mujer Ind\u00edgena\" en la regi\u00f3n de las Tres Huastecas","og_url":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/","og_site_name":"Alas Medios","article_published_time":"2024-08-25T20:22:13+00:00","article_modified_time":"2024-08-25T20:22:15+00:00","og_image":[{"width":2048,"height":1357,"url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg","type":"image\/jpeg"}],"author":"Keila Rodr\u00edguez Pe\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Keila Rodr\u00edguez Pe\u00f1a","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#article","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/"},"author":{"name":"Keila Rodr\u00edguez Pe\u00f1a","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34"},"headline":"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco","datePublished":"2024-08-25T20:22:13+00:00","dateModified":"2024-08-25T20:22:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg","articleSection":["Inicio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/","url":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/","name":"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#primaryimage"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg","datePublished":"2024-08-25T20:22:13+00:00","dateModified":"2024-08-25T20:22:15+00:00","description":"La CEDSPI ha tomado una iniciativa fundamental al concretar la creaci\u00f3n de la \"Casa de la Mujer Ind\u00edgena\" en la regi\u00f3n de las Tres Huastecas","breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#primaryimage","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2024\/08\/FOTO-24_AGOSTO_2024_PUEBLOS-INDIGENAS_PROYECTO-CASA-DE-LA-MUJER-INDIGENA_PARTERAS.-4.jpg","width":2048,"height":1357},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/2024\/08\/25\/lanzan-proyecto-de-la-casa-de-la-mujer-indigena-en-atlapexco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"Lanzan proyecto de la Casa de la Mujer Ind\u00edgena en Atlapexco"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34","name":"Keila Rodr\u00edguez Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","caption":"Keila Rodr\u00edguez Pe\u00f1a"},"sameAs":["http:\/\/www.alasmedios.com"],"url":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/1862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/comments?post=1862"}],"version-history":[{"count":1,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/1862\/revisions"}],"predecessor-version":[{"id":1872,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/1862\/revisions\/1872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media\/1863"}],"wp:attachment":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media?parent=1862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/categories?post=1862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags?post=1862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}