{"id":11136,"date":"2026-07-17T04:00:00","date_gmt":"2026-07-17T10:00:00","guid":{"rendered":"https:\/\/www.alasmedios.com\/?p=11136"},"modified":"2026-07-16T15:28:12","modified_gmt":"2026-07-16T21:28:12","slug":"derecho-al-voto-o-del-que-otros-decidan","status":"publish","type":"post","link":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/","title":{"rendered":"Derecho al voto o del que otros decidan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Todo discurso que se pronuncie para quitarle el derecho a alguien jam\u00e1s estar\u00e1 lo suficientemente lejos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde siempre el <strong>conservadurismo <\/strong>ha querido quitarle <strong>libertades <\/strong>y <strong>derechos <\/strong>a las <strong>mujeres<\/strong>, minor\u00edas y todo ser en el que no se ve reflejado; cuando<strong> Donald Trump <\/strong>lleg\u00f3 por segunda vez a la presidencia de<strong> Estados Unidos<\/strong> lo hizo con un <strong>discurso cargado de odio<\/strong>, basta con recordar lo que sus votantes pregonaron:<strong> <a href=\"https:\/\/www.alasmedios.com\/index.php\/2024\/11\/12\/auge-del-acoso-digital-a-mujeres-tras-victoria-de-trump-tu-cuerpo-mi-decision\/\" data-type=\"post\" data-id=\"2580\">\u201cTu cuerpo, mi decisi\u00f3n\u201d<\/a><\/strong>; meses despu\u00e9s las estadounidenses perdieron el <strong>derecho al aborto<\/strong> en casi todo su pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y as\u00ed han pasado los a\u00f1os, ahora con<strong> redadas contra migrantes, censura en libros, derechos de las personas LGBTTTIQA+ arrebatados, la religi\u00f3n en las escuelas<\/strong>; fue cuesti\u00f3n de tiempo para que alguien pronunciara lo que se ven\u00eda gestando: <em><strong>\u00bfy si le quitamos el derecho al voto a las mujeres?<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00c1S DE POR ELLAS: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/05\/15\/quien-cuida-a-las-infancias\/\" data-type=\"post\" data-id=\"9147\">\u00bfQui\u00e9n cuida a las infancias?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Erika Kirk<\/strong> es la mensajera y rostro de esta oleada: una mujer rica, empresaria y viuda, es quien ahora, a todo pulm\u00f3n pide volver al<strong> voto familiar<\/strong>. Y en <strong>M\u00e9xico<\/strong>, el <strong>PAN <\/strong>no tard\u00f3 en hacer eco. Quiz\u00e1 porque nuestros problemas son otros el eco se contiene en cierto sector, pero no lo hace menos peligroso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 pasa cuando se comienza a cuestionar el derecho y libertad de otros?<\/strong> Cuando el <strong>racismo, misoginia, machismo, LGBTfobia<\/strong> y <strong>clasismo <\/strong>comienzan a ser aceptados, minimizados y normalizados tenemos como resultado esto: pol\u00edticos y personalidades con poder que sienten que son libres de proponer prohibiciones a otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, toda persona tiene <strong>derecho al voto<\/strong>; toda <strong>mujer <\/strong>tiene<strong> derecho al voto<\/strong> (&#8230;al menos en <strong>M\u00e9xico<\/strong>); y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: <strong>decidir<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pon en duda el <strong>derecho al voto<\/strong> y pondr\u00e1s en duda la<strong> autodeterminaci\u00f3n, libertad de tr\u00e1nsito, con qui\u00e9n relacionarte, libertad de expresi\u00f3n, derechos reproductivos; pon en duda el derecho a decidir y pondr\u00e1s en duda lo que implica ser humano, ser persona, ser ciudadana y con ello todos los dem\u00e1s derechos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TE PUEDE INTERESAR: <a href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/04\/15\/firmaron-otros-crearon-ellas-tres-artistas-borradas-por-hombres\/\" data-type=\"post\" data-id=\"8597\">Firmaron otros, crearon ellas: tres artistas borradas por hombres<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los<strong> discursos de odio<\/strong> se propagan y es necesario buscar frenarlos: no, <strong>la libertad de expresi\u00f3n no arropa injurias.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las mujeres somos capaces<\/strong>, no necesitamos un tutor, <strong>no necesitamos que alguien vote por nosotras: somos capaces de decidir.<\/strong> No callar, expresarnos, negarnos a aceptar discursos mis\u00f3ginos, visibilizar desigualdades, estigmas y estereotipos es una forma de <strong>luchar contra las ideas de segregaci\u00f3n, es defenderse.<\/strong><\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/Infrasestructura-y-proyectos-en-Hidalgo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/hidalgo-suma-147-mil-mdp-en-inversiones-y-preve-191-mil-empleos\/\">Hidalgo suma 147 mil mdp en inversiones y prev\u00e9 191 mil empleos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/06\/MARIA-ELENA-ORTEGA-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Mar\u00eda Elena Ortega\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/la-magia-de-las-cosas-ordinarias\/\">La magia de las cosas ordinarias<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/Melissa-Marquez-y-Aylin-Ibarra-con-el-oro-del-Campeonato-Mundial-de-Remo-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/melissa-marquez-y-aylin-ibarra-regresan-a-mexico-con-el-oro-del-mundial-de-remo\/\">Melissa M\u00e1rquez y Aylin Ibarra regresan a M\u00e9xico con el oro del Mundial de Remo<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Todo discurso que se pronuncie para quitarle el derecho a alguien jam\u00e1s estar\u00e1 lo suficientemente lejos. Desde siempre el conservadurismo<\/p>\n","protected":false},"author":4,"featured_media":9148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","iawp_total_views":15,"footnotes":""},"categories":[3523],"tags":[2150,456,107,53,595],"class_list":["post-11136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-por-ellas-keila-rodriguez","tag-derecho-al-voto","tag-derechos","tag-keila-itzel-rodriguez-pena","tag-mujeres","tag-por-ellas"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-150x150.jpeg","medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-300x182.jpeg","medium_large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-768x466.jpeg","large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-1024x621.jpeg","1536x1536":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-1536x932.jpeg","2048x2048":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg","colormag-highlighted-post":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-392x272.jpeg","colormag-featured-post-medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-390x205.jpeg","colormag-featured-post-small":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-130x90.jpeg","colormag-featured-image":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-800x445.jpeg","colormag-default-news":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-150x150.jpeg","colormag-featured-image-large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-1400x600.jpeg"},"magazineBlocksPostAuthor":{"name":"Keila Rodr\u00edguez Pe\u00f1a","avatar":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"1","magazineBlocksPostExcerpt":"Todo discurso que se pronuncie para quitarle el derecho a alguien jam\u00e1s estar\u00e1 lo suficientemente lejos. Desde siempre el conservadurismo","magazineBlocksPostCategories":["Por ellas - Keila Rodr\u00edguez"],"magazineBlocksPostViewCount":63,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg",1600,971,false],"medium":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-300x182.jpeg",300,182,true],"thumbnail":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS-150x150.jpeg",150,150,true]},"magazine_blocks_author":{"display_name":"Keila Rodr\u00edguez Pe\u00f1a","author_link":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"},"magazine_blocks_comment":1,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-3523\">Por ellas - Keila Rodr\u00edguez<\/a>","videoUrl":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Derecho al voto o del que otros decidan<\/title>\r\n<meta name=\"description\" content=\"Toda mujer tiene derecho al voto; y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: decidir.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Derecho al voto o del que otros decidan\" \/>\r\n<meta property=\"og:description\" content=\"Toda mujer tiene derecho al voto; y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: decidir.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-07-17T10:00:00+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\r\n\t<meta property=\"og:image:height\" content=\"971\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Keila Rodr\u00edguez Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/\"},\"author\":{\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\"},\"headline\":\"Derecho al voto o del que otros decidan\",\"datePublished\":\"2026-07-17T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/\"},\"wordCount\":440,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg\",\"keywords\":[\"derecho al voto\",\"derechos\",\"Keila Itzel Rodr\u00edguez Pe\u00f1a\",\"Mujeres\",\"Por ellas\"],\"articleSection\":[\"Por ellas - Keila Rodr\u00edguez\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/\",\"name\":\"Derecho al voto o del que otros decidan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg\",\"datePublished\":\"2026-07-17T10:00:00+00:00\",\"description\":\"Toda mujer tiene derecho al voto; y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: decidir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg\",\"width\":1600,\"height\":971,\"caption\":\"Por ellas. Keila Rodr\u00edguez Pe\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/17\\\/derecho-al-voto-o-del-que-otros-decidan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derecho al voto o del que otros decidan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/0ba31bdd19a05ebf5c7fef1fedf99c34\",\"name\":\"Keila Rodr\u00edguez Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g\",\"caption\":\"Keila Rodr\u00edguez Pe\u00f1a\"},\"sameAs\":[\"http:\\\/\\\/www.alasmedios.com\"],\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/author\\\/keila\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Derecho al voto o del que otros decidan","description":"Toda mujer tiene derecho al voto; y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: decidir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/","og_locale":"es_MX","og_type":"article","og_title":"Derecho al voto o del que otros decidan","og_description":"Toda mujer tiene derecho al voto; y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: decidir.","og_url":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/","og_site_name":"Alas Medios","article_published_time":"2026-07-17T10:00:00+00:00","og_image":[{"width":1600,"height":971,"url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg","type":"image\/jpeg"}],"author":"Keila Rodr\u00edguez Pe\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Keila Rodr\u00edguez Pe\u00f1a","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#article","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/"},"author":{"name":"Keila Rodr\u00edguez Pe\u00f1a","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34"},"headline":"Derecho al voto o del que otros decidan","datePublished":"2026-07-17T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/"},"wordCount":440,"commentCount":1,"publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg","keywords":["derecho al voto","derechos","Keila Itzel Rodr\u00edguez Pe\u00f1a","Mujeres","Por ellas"],"articleSection":["Por ellas - Keila Rodr\u00edguez"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/","url":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/","name":"Derecho al voto o del que otros decidan","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#primaryimage"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg","datePublished":"2026-07-17T10:00:00+00:00","description":"Toda mujer tiene derecho al voto; y en este derecho se engloba una de las m\u00e1s esenciales y primigenias libertades: decidir.","breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#primaryimage","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/05\/KEILA-RODRIGUEZ-PENA-POR-ELLAS.jpeg","width":1600,"height":971,"caption":"Por ellas. Keila Rodr\u00edguez Pe\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/17\/derecho-al-voto-o-del-que-otros-decidan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"Derecho al voto o del que otros decidan"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/0ba31bdd19a05ebf5c7fef1fedf99c34","name":"Keila Rodr\u00edguez Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2553a2bfaa601b9d539b617c8793e151bdffb60f9e48a249912f86d4c9ebeef?s=96&d=mm&r=g","caption":"Keila Rodr\u00edguez Pe\u00f1a"},"sameAs":["https:\/\/www.alasmedios.com"],"url":"https:\/\/www.alasmedios.com\/index.php\/author\/keila\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/11136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/comments?post=11136"}],"version-history":[{"count":1,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/11136\/revisions"}],"predecessor-version":[{"id":11143,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/11136\/revisions\/11143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media\/9148"}],"wp:attachment":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media?parent=11136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/categories?post=11136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags?post=11136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}