{"id":11067,"date":"2026-07-16T10:53:26","date_gmt":"2026-07-16T16:53:26","guid":{"rendered":"https:\/\/www.alasmedios.com\/?p=11067"},"modified":"2026-07-16T11:20:35","modified_gmt":"2026-07-16T17:20:35","slug":"buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla","status":"publish","type":"post","link":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/","title":{"rendered":"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quienes quieran aprovechar las <strong>vacaciones <\/strong>para desarrollar su <strong>creatividad <\/strong>ya pueden inscribirse a los <strong>Talleres de Iniciaci\u00f3n Art\u00edstica &#8220;Profesor Pedro \u00c1ngel Palou P\u00e9rez&#8221;<\/strong>, una propuesta que re\u00fane actividades <strong>presenciales y virtuales<\/strong> para personas de distintas edades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oferta incluye cursos de <strong>danza, m\u00fasica, artes pl\u00e1sticas, teatro, literatura, fotograf\u00eda, artes audiovisuales, ajedrez y arte circense<\/strong>. Adem\u00e1s, algunos talleres ser\u00e1n <strong>gratuitos <\/strong>y otros tendr\u00e1n una<strong> cuota de recuperaci\u00f3n.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Opciones para todas las edades<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las actividades est\u00e1n dirigidas a <strong>ni\u00f1as, ni\u00f1os, j\u00f3venes, personas adultas y mayores de 60 a\u00f1os<\/strong>, con el objetivo de acercar la formaci\u00f3n art\u00edstica a p\u00fablicos diversos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n habr\u00e1 <strong>talleres gratuitos en la Casa J\u00f3venes en Progreso<\/strong>, ubicada en San Andr\u00e9s Cholula, para ampliar las oportunidades de participaci\u00f3n.<\/p>\n\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo inscribirse?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>inscripciones <\/strong>permanecer\u00e1n abiertas hasta el <strong>27 de julio<\/strong> o hasta agotar los lugares disponibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>registro presencial<\/strong> se realiza en las instalaciones de los talleres, ubicadas en la<strong> 7 Oriente n\u00famero 2, en el Centro Hist\u00f3rico de Puebla.<\/strong> Quienes deseen participar en las modalidades virtuales pueden solicitar el formato de inscripci\u00f3n a trav\u00e9s del correo <strong>tallerespedroangelpalou@puebla.gob.mx.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los <strong>requisitos <\/strong>se encuentran<strong> acta de nacimiento, CURP, certificado m\u00e9dico simple con tipo de sangre y el formato de inscripci\u00f3n<\/strong>. Los talleres con costo tienen una cuota de recuperaci\u00f3n de 615 pesos, adem\u00e1s de una credencial con valor de 39 pesos, documento que tambi\u00e9n se solicita para los cursos gratuitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los talleres se desarrollar\u00e1n del <strong>20 de julio al 13 de septiembre.<\/strong><\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/Mujeres-afectadas-en-China-y-Nepal-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/43-mil-mujeres-y-ninas-necesitan-ayuda-tras-las-inundaciones-en-nepal\/\">43 mil mujeres y ni\u00f1as necesitan ayuda tras las inundaciones en Nepal<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/09\/Infrasestructura-y-proyectos-en-Hidalgo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/hidalgo-suma-147-mil-mdp-en-inversiones-y-preve-191-mil-empleos\/\">Hidalgo suma 147 mil mdp en inversiones y prev\u00e9 191 mil empleos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/06\/MARIA-ELENA-ORTEGA-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Mar\u00eda Elena Ortega\" style=\"\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/09\/02\/la-magia-de-las-cosas-ordinarias\/\">La magia de las cosas ordinarias<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica &#8220;Profesor Pedro<\/p>\n","protected":false},"author":18,"featured_media":11065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","iawp_total_views":3,"footnotes":""},"categories":[3704],"tags":[],"class_list":["post-11067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-150x150.jpeg","medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-300x200.jpeg","medium_large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-768x512.jpeg","large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-1024x683.jpeg","1536x1536":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","2048x2048":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","colormag-highlighted-post":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-392x272.jpeg","colormag-featured-post-medium":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-390x205.jpeg","colormag-featured-post-small":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-130x90.jpeg","colormag-featured-image":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-800x445.jpeg","colormag-default-news":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-150x150.jpeg","colormag-featured-image-large":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-1200x600.jpeg"},"magazineBlocksPostAuthor":{"name":"Yissel Padilla","avatar":"https:\/\/secure.gravatar.com\/avatar\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica &#8220;Profesor Pedro","magazineBlocksPostCategories":["Puebla"],"magazineBlocksPostViewCount":45,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg",1200,800,false],"medium":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-300x200.jpeg",300,200,true],"thumbnail":["https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2-150x150.jpeg",150,150,true]},"magazine_blocks_author":{"display_name":"Yissel Padilla","author_link":"https:\/\/www.alasmedios.com\/index.php\/author\/yissel-padilla\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-3704\">Puebla<\/a>","videoUrl":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla - Alas Medios<\/title>\r\n<meta name=\"description\" content=\"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica &quot;Profesor Pedro \u00c1ngel Palou P\u00e9rez&quot;, una propuesta que re\u00fane actividades presenciales y virtuales para personas de distintas edades.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_MX\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla - Alas Medios\" \/>\r\n<meta property=\"og:description\" content=\"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica &quot;Profesor Pedro \u00c1ngel Palou P\u00e9rez&quot;, una propuesta que re\u00fane actividades presenciales y virtuales para personas de distintas edades.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Alas Medios\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-07-16T16:53:26+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-07-16T17:20:35+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"800\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Yissel Padilla\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yissel Padilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/\"},\"author\":{\"name\":\"Yissel Padilla\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/4a77b9da264b9fd30e9b7bf44efa7ada\"},\"headline\":\"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla\",\"datePublished\":\"2026-07-16T16:53:26+00:00\",\"dateModified\":\"2026-07-16T17:20:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/talleres-artisticos-2.jpeg\",\"articleSection\":[\"Puebla\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/\",\"name\":\"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla - Alas Medios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/talleres-artisticos-2.jpeg\",\"datePublished\":\"2026-07-16T16:53:26+00:00\",\"dateModified\":\"2026-07-16T17:20:35+00:00\",\"description\":\"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica \\\"Profesor Pedro \u00c1ngel Palou P\u00e9rez\\\", una propuesta que re\u00fane actividades presenciales y virtuales para personas de distintas edades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/talleres-artisticos-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/talleres-artisticos-2.jpeg\",\"width\":1200,\"height\":800,\"caption\":\"Foto: Especial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/2026\\\/07\\\/16\\\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.alasmedios.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#website\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"name\":\"Alas Medios\",\"description\":\"Alas para pensar, Alas para volar, Alas de libertad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alasmedios.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#organization\",\"name\":\"Alas Medios\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.alasmedios.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-cropped-GAM-1.png\",\"width\":467,\"height\":235,\"caption\":\"Alas Medios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alasmedios.com\\\/#\\\/schema\\\/person\\\/4a77b9da264b9fd30e9b7bf44efa7ada\",\"name\":\"Yissel Padilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g\",\"caption\":\"Yissel Padilla\"},\"url\":\"https:\\\/\\\/www.alasmedios.com\\\/index.php\\\/author\\\/yissel-padilla\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla - Alas Medios","description":"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica \"Profesor Pedro \u00c1ngel Palou P\u00e9rez\", una propuesta que re\u00fane actividades presenciales y virtuales para personas de distintas edades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla - Alas Medios","og_description":"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica \"Profesor Pedro \u00c1ngel Palou P\u00e9rez\", una propuesta que re\u00fane actividades presenciales y virtuales para personas de distintas edades.","og_url":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/","og_site_name":"Alas Medios","article_published_time":"2026-07-16T16:53:26+00:00","article_modified_time":"2026-07-16T17:20:35+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","type":"image\/jpeg"}],"author":"Yissel Padilla","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Yissel Padilla","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#article","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/"},"author":{"name":"Yissel Padilla","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/4a77b9da264b9fd30e9b7bf44efa7ada"},"headline":"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla","datePublished":"2026-07-16T16:53:26+00:00","dateModified":"2026-07-16T17:20:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","articleSection":["Puebla"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/","url":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/","name":"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla - Alas Medios","isPartOf":{"@id":"https:\/\/www.alasmedios.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#primaryimage"},"image":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","datePublished":"2026-07-16T16:53:26+00:00","dateModified":"2026-07-16T17:20:35+00:00","description":"Quienes quieran aprovechar las vacaciones para desarrollar su creatividad ya pueden inscribirse a los Talleres de Iniciaci\u00f3n Art\u00edstica \"Profesor Pedro \u00c1ngel Palou P\u00e9rez\", una propuesta que re\u00fane actividades presenciales y virtuales para personas de distintas edades.","breadcrumb":{"@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#primaryimage","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/07\/talleres-artisticos-2.jpeg","width":1200,"height":800,"caption":"Foto: Especial"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alasmedios.com\/index.php\/2026\/07\/16\/buscas-un-plan-para-estas-vacaciones-inscribete-a-los-talleres-de-arte-en-puebla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.alasmedios.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfBuscas un plan para estas vacaciones? Inscr\u00edbete a los talleres de arte en Puebla"}]},{"@type":"WebSite","@id":"https:\/\/www.alasmedios.com\/#website","url":"https:\/\/www.alasmedios.com\/","name":"Alas Medios","description":"Alas para pensar, Alas para volar, Alas de libertad","publisher":{"@id":"https:\/\/www.alasmedios.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alasmedios.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alasmedios.com\/#organization","name":"Alas Medios","url":"https:\/\/www.alasmedios.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","contentUrl":"https:\/\/www.alasmedios.com\/wp-content\/uploads\/2026\/01\/cropped-cropped-GAM-1.png","width":467,"height":235,"caption":"Alas Medios"},"image":{"@id":"https:\/\/www.alasmedios.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alasmedios.com\/#\/schema\/person\/4a77b9da264b9fd30e9b7bf44efa7ada","name":"Yissel Padilla","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98842131f4e7c39771d95c321b4e271e6d6b9aefdb1d69d099b18469d859168e?s=96&d=mm&r=g","caption":"Yissel Padilla"},"url":"https:\/\/www.alasmedios.com\/index.php\/author\/yissel-padilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/11067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/comments?post=11067"}],"version-history":[{"count":2,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/11067\/revisions"}],"predecessor-version":[{"id":11079,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/posts\/11067\/revisions\/11079"}],"wp:attachment":[{"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/media?parent=11067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/categories?post=11067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alasmedios.com\/index.php\/wp-json\/wp\/v2\/tags?post=11067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}